{"id":3,"count":0,"description":"","link":"https:\/\/www.wpksakon.ac.th\/home\/category\/%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%90%e0%b8%b2%e0%b8%99\/","name":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19","slug":"%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%90%e0%b8%b2%e0%b8%99","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}