{"id":8,"count":1,"description":"","link":"https:\/\/www.wpksakon.ac.th\/home\/category\/news\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b8%e0%b8%84%e0%b8%84%e0%b8%a5\/","name":"\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25","slug":"%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b8%e0%b8%84%e0%b8%84%e0%b8%a5","taxonomy":"category","parent":1,"meta":[],"_links":{"self":[{"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/categories\/1"}],"wp:post_type":[{"href":"https:\/\/www.wpksakon.ac.th\/home\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}